{"id":44265,"count":25,"description":"","link":"https:\/\/cycle.rizoma.com\/de\/motorbike\/harley-davidson\/road-glide\/107-road-glide-2017-fltrx\/","name":"107 Road Glide (2017) - FLTRX","slug":"107-road-glide-2017-fltrx","taxonomy":"rizoma_bike","parent":44031,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/cycle.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike\/44265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cycle.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike"}],"about":[{"href":"https:\/\/cycle.rizoma.com\/de\/wp-json\/wp\/v2\/taxonomies\/rizoma_bike"}],"up":[{"embeddable":true,"href":"https:\/\/cycle.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike\/44031"}],"wp:post_type":[{"href":"https:\/\/cycle.rizoma.com\/de\/wp-json\/wp\/v2\/product?rizoma_bike=44265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}